{"id":10436,"date":"2025-11-19T22:24:57","date_gmt":"2025-11-20T01:24:57","guid":{"rendered":"https:\/\/casadoseguro.org.br\/?p=10436"},"modified":"2025-11-19T22:40:13","modified_gmt":"2025-11-20T01:40:13","slug":"do-risco-ao-planejamento-como-seguros-ciencia-e-municipios-estao-moldando-a-resiliencia-climatica","status":"publish","type":"post","link":"https:\/\/casadoseguro.org.br\/en\/do-risco-ao-planejamento-como-seguros-ciencia-e-municipios-estao-moldando-a-resiliencia-climatica\/","title":{"rendered":"Do risco ao planejamento: como seguros, ci\u00eancia e munic\u00edpios est\u00e3o moldando a resili\u00eancia clim\u00e1tica"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10436\" class=\"elementor elementor-10436\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdc5834 e-con-full she-header-yes she-header-transparent-yes e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"bdc5834\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;transparent&quot;:&quot;yes&quot;,&quot;scroll_distance&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;transparent_header_show&quot;:&quot;yes&quot;,&quot;background_show&quot;:&quot;yes&quot;,&quot;background&quot;:&quot;#001A0AFC&quot;,&quot;transparent_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;scroll_distance_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;scroll_distance_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;she_offset_top_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_offset_top_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;she_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;she_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:0,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:0,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;she_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\">\n\t\t<div class=\"elementor-element elementor-element-acd5b9c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"acd5b9c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bedcdfc e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"bedcdfc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1490aad elementor-widget elementor-widget-image\" data-id=\"1490aad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/03\/Estrela.png\" class=\"attachment-large size-large wp-image-165\" alt=\"\" srcset=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/03\/Estrela.png 300w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/03\/Estrela-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6750959 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"6750959\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfce3d9 elementor-nav-menu__align-end elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"bfce3d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;svg aria-hidden=\\&quot;true\\&quot; class=\\&quot;e-font-icon-svg e-fas-caret-down\\&quot; viewBox=\\&quot;0 0 320 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.3 192h257.3c17.8 0 26.7 21.5 14.1 34.1L174.1 354.8c-7.8 7.8-20.5 7.8-28.3 0L17.2 226.1C4.6 213.5 13.5 192 31.3 192z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-bfce3d9\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-348\"><a href=\"https:\/\/casadoseguro.org.br\/\" class=\"elementor-item\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-350\"><a href=\"https:\/\/casadoseguro.org.br\/#sobre\" class=\"elementor-item elementor-item-anchor\">SOBRE<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-375\"><a href=\"https:\/\/casadoseguro.org.br\/#EMPODERADORES\" class=\"elementor-item elementor-item-anchor\">EMPODERADORES<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1113\"><a href=\"https:\/\/casadoseguro.org.br\/#imprensa\" class=\"elementor-item elementor-item-anchor\">Not\u00edcias<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1114\"><a href=\"https:\/\/casadoseguro.org.br\/#CONTATO\" class=\"elementor-item elementor-item-anchor\">CONTATO<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-349\"><a href=\"https:\/\/tshop.proevento.com.br\/?id=Y25zZWdfZGFkb3M6MTcz&#038;csp=645&#038;tp=i\" class=\"elementor-item\">Inscri\u00e7\u00f5es Abertas<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open e-font-icon-svg e-eicon-menu-bar\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M104 333H896C929 333 958 304 958 271S929 208 896 208H104C71 208 42 237 42 271S71 333 104 333ZM104 583H896C929 583 958 554 958 521S929 458 896 458H104C71 458 42 487 42 521S71 583 104 583ZM104 833H896C929 833 958 804 958 771S929 708 896 708H104C71 708 42 737 42 771S71 833 104 833Z\"><\/path><\/svg><svg aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close e-font-icon-svg e-eicon-close\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M742 167L500 408 258 167C246 154 233 150 217 150 196 150 179 158 167 167 154 179 150 196 150 212 150 229 154 242 171 254L408 500 167 742C138 771 138 800 167 829 196 858 225 858 254 829L496 587 738 829C750 842 767 846 783 846 800 846 817 842 829 829 842 817 846 804 846 783 846 767 842 750 829 737L588 500 833 258C863 229 863 200 833 171 804 137 775 137 742 167Z\"><\/path><\/svg>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-bfce3d9\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-348\"><a href=\"https:\/\/casadoseguro.org.br\/\" class=\"elementor-item\" tabindex=\"-1\">HOME<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-350\"><a href=\"https:\/\/casadoseguro.org.br\/#sobre\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">SOBRE<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-375\"><a href=\"https:\/\/casadoseguro.org.br\/#EMPODERADORES\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">EMPODERADORES<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1113\"><a href=\"https:\/\/casadoseguro.org.br\/#imprensa\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">Not\u00edcias<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-1114\"><a href=\"https:\/\/casadoseguro.org.br\/#CONTATO\" class=\"elementor-item elementor-item-anchor\" tabindex=\"-1\">CONTATO<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-349\"><a href=\"https:\/\/tshop.proevento.com.br\/?id=Y25zZWdfZGFkb3M6MTcz&#038;csp=645&#038;tp=i\" class=\"elementor-item\" tabindex=\"-1\">Inscri\u00e7\u00f5es Abertas<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-214995f e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"214995f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-27f3612e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"27f3612e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79a2312 elementor-widget elementor-widget-spacer\" data-id=\"79a2312\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e891cf1 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"e891cf1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-78bbf5c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"78bbf5c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e2a627 elementor-widget elementor-widget-jkit_post_featured_image\" data-id=\"7e2a627\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_post_featured_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-post-featured-image jeg_module___6a04f68c945ca\" ><div class=\"post-featured-image \"><a href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde.jpg\"><img decoding=\"async\" width=\"800\" height=\"354\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde.jpg 1333w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde-300x133.jpg 300w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde-768x340.jpg 768w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde-18x8.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bea1586 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"bea1586\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Do risco ao planejamento: como seguros, ci\u00eancia e munic\u00edpios est\u00e3o moldando a resili\u00eancia clim\u00e1tica<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-560ff5f wpr-post-info-align-left elementor-widget elementor-widget-wpr-post-info\" data-id=\"560ff5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpr-post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"wpr-post-info wpr-post-info-horizontal\"><li class=\"wpr-post-info-date\"><span class=\"wpr-post-info-text\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg><\/span><span>19\/11\/2025<\/span><\/li><\/ul>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8b9b5 elementor-widget elementor-widget-text-editor\" data-id=\"7b8b9b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conhecer o risco \u00e9 o primeiro passo\u00a0para evit\u00e1-lo. E\u00a0o Brasil n\u00e3o pode mais caminhar \u00e0s cegas diante dos eventos clim\u00e1ticos extremos. Essa foi a mensagem central de Dyogo Oliveira, presidente da CNseg (Confedera\u00e7\u00e3o\u00a0Nacional das Seguradoras), na abertura do <strong>\u201cF\u00f3rum Cidades Resilientes na COP30\u201d<\/strong>, realizado na tarde\u00a0desta quarta-feira (19), na Casa do Seguro, em Bel\u00e9m (PA), durante\u00a0a Confer\u00eancia do Clima.\u00a0<\/p>\n<p>O evento, promovido pela CNseg em parceria com a Confedera\u00e7\u00e3o Nacional de\u00a0Munic\u00edpios (CNM), reuniu lideran\u00e7as para\u00a0discutir como a coopera\u00e7\u00e3o entre\u00a0governos, mercado\u00a0segurador e sociedade pode transformar os\u00a0desafios clim\u00e1ticos em oportunidades,\u00a0promovendo cidades mais preparadas e adaptadas para a\u00a0transi\u00e7\u00e3o clim\u00e1tica.<\/p>\n<p>Na abertura, Dyogo Oliveira anunciou o <a href=\"https:\/\/cnseg.org.br\/noticias\/cop-30-c-nseg-lanca-ferramenta-regionalizada-contra-risco-de-inundacao\">lan\u00e7amento da Ferramenta de Avalia\u00e7\u00e3o de Riscos Clim\u00e1ticos<\/a>, uma solu\u00e7\u00e3o digital desenvolvida pela CNseg para calcular o risco de inunda\u00e7\u00e3o de qualquer endere\u00e7o do pa\u00eds a partir do CEP. A ferramenta, que futuramente estar\u00e1 aberta ao p\u00fablico, cruza dados de diversas bases oficiais e gera um <i>score<\/i> de risco. \u201c\u00c9 uma contribui\u00e7\u00e3o concreta para que as pessoas entendam a exposi\u00e7\u00e3o em que vivem e possam agir preventivamente\u201d, destacou. Ele tamb\u00e9m refor\u00e7ou a proposta da CNseg de cria\u00e7\u00e3o de um seguro social de cat\u00e1strofe, que pode garantir indeniza\u00e7\u00f5es emergenciais para fam\u00edlias afetadas por enchentes e deslizamentos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b49b4f elementor-widget elementor-widget-image\" data-id=\"6b49b4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"354\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/1-1-2000x885.jpg\" class=\"attachment-large size-large wp-image-10439\" alt=\"\" srcset=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/1-1-2000x885.jpg 2000w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/1-1-300x133.jpg 300w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/1-1-768x340.jpg 768w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/1-1-1536x680.jpg 1536w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/1-1-2048x906.jpg 2048w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/1-1-18x8.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">N\u00e9lio Aguiar, diretor da CNM<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b4ca5f elementor-widget elementor-widget-text-editor\" data-id=\"6b4ca5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Em sua fala, Dyogo refor\u00e7ou que, entre 2022 e 2024, o Brasil sofreu mais de R$ 200 bilh\u00f5es em perdas econ\u00f4micas decorrentes de eventos clim\u00e1ticos extremos. O n\u00famero de ocorr\u00eancias quase dobrou em uma d\u00e9cada, passando de 2.500 para 4.500 por ano. Para o representante da CNseg, enfrentar riscos dessa magnitude exigir\u00e1 coopera\u00e7\u00e3o cont\u00ednua entre governo, setor segurador e sociedade. \u201cN\u00e3o se trata de infraestrutura. Trata-se de proteger vidas\u201d, afirmou.<\/p>\n<p><strong>O alerta dos munic\u00edpios<\/strong><\/p>\n<p>Representando a CNM, N\u00e9lio Aguiar trouxe a perspectiva urgente de quem vive o impacto das mudan\u00e7as clim\u00e1ticas no cotidiano das cidades. Ele destacou que, nos \u00faltimos 12 anos, os munic\u00edpios acumularam R$ 700 bilh\u00f5es em preju\u00edzos com desastres naturais.\u00a0<\/p>\n<p>Apenas nos primeiros quatro meses de 2025, j\u00e1 s\u00e3o R$ 28,5 bilh\u00f5es, com 115 mortes, milhares de desabrigados e desalojados em todo o pa\u00eds. Aguiar defendeu mais estrutura, tecnologia e autonomia para os munic\u00edpios, al\u00e9m da cria\u00e7\u00e3o de inst\u00e2ncias nacionais de coordena\u00e7\u00e3o, como a PEC 31\/2024, que institui o Conselho Nacional de Gest\u00e3o Clim\u00e1tica e Preven\u00e7\u00e3o de Desastres. Ao elogiar o lan\u00e7amento da ferramenta da CNseg, Aguiar refor\u00e7ou: \u201cGestores precisam de indicadores na palma da m\u00e3o para tomar decis\u00f5es certas, especialmente em emerg\u00eancias\u201d.<\/p>\n<p><strong>A vis\u00e3o do Minist\u00e9rio das Cidades<\/strong><\/p>\n<p>O ministro das Cidades, Jader Barbalho Filho, destacou a urg\u00eancia de inserir gestores municipais, prefeitos e lideran\u00e7as comunit\u00e1rias no centro das decis\u00f5es clim\u00e1ticas. Para ele, nenhum plano ser\u00e1 efetivo se aqueles que executam as pol\u00edticas na ponta n\u00e3o estiverem envolvidos desde o in\u00edcio. \u201cSem os l\u00edderes locais, n\u00e3o h\u00e1 implementa\u00e7\u00e3o poss\u00edvel\u201d, afirmou, lembrando que 87% da popula\u00e7\u00e3o brasileira vive em \u00e1reas urbanas e que a crise clim\u00e1tica exige tanto a redu\u00e7\u00e3o do desmatamento quanto a diminui\u00e7\u00e3o das emiss\u00f5es que partem das cidades.\u00a0<\/p>\n<p>O ministro refor\u00e7ou as a\u00e7\u00f5es do Governo Federal em preven\u00e7\u00e3o, como obras de macrodrenagem e conten\u00e7\u00e3o de encostas, e defendeu que a COP30 seja simultaneamente a \u201cCOP das florestas\u201d e a \u201cCOP das cidades\u201d. Ele destacou experi\u00eancias internacionais e o papel crescente de governadores e prefeitos no combate \u00e0 crise clim\u00e1tica, afirmando que o Brasil tamb\u00e9m precisa fortalecer esse protagonismo. \u201cO planeta pede urg\u00eancia\u201d, concluiu.<\/p>\n<p><strong>Do planejamento \u00e0 pr\u00e1tica: resili\u00eancia, seguros e solu\u00e7\u00f5es inteligentes<\/strong><\/p>\n<p>No painel <strong>\u201cPara inspirar: do planejamento \u00e0 pr\u00e1tica &#8211; resili\u00eancia, seguros e solu\u00e7\u00f5es inteligentes\u201d<\/strong>, o moderador Paulo Nobre, climatologista do Instituto Nacional de Pesquisas Espaciais (INPE), abriu a discuss\u00e3o lembrando que a ci\u00eancia j\u00e1 aponta um futuro de extremos mais intensos e frequentes. Ele sintetizou o desafio em uma frase que guiou o debate. \u201cA adapta\u00e7\u00e3o \u00e9 local, cidade a cidade, bacia hidrogr\u00e1fica a bacia hidrogr\u00e1fica.\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae772f4 elementor-widget elementor-widget-image\" data-id=\"ae772f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"354\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/2-2000x885.jpg\" class=\"attachment-large size-large wp-image-10440\" alt=\"\" srcset=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/2-2000x885.jpg 2000w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/2-300x133.jpg 300w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/2-768x340.jpg 768w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/2-1536x680.jpg 1536w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/2-2048x906.jpg 2048w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/2-18x8.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Painel 2- Planejar, Construir e Cuidar: Estrat\u00e9gias Municipais Para a Promo\u00e7\u00e3o de Infraestruturas Resilientes<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f39045 elementor-widget elementor-widget-text-editor\" data-id=\"7f39045\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A prefeita Elis\u00e2ngela Paiva Celestino, de Conc\u00f3rdia do Par\u00e1 (PA), destacou a dificuldade de munic\u00edpios de pequeno porte em acessar financiamento, estruturar equipes t\u00e9cnicas e realizar a\u00e7\u00f5es preventivas. Ela apresentou iniciativas de seu munic\u00edpio, como a cria\u00e7\u00e3o de uma unidade de conserva\u00e7\u00e3o, o projeto do primeiro bairro sustent\u00e1vel da Amaz\u00f4nia e programas de reaproveitamento de res\u00edduos, exemplos que conectam preserva\u00e7\u00e3o ambiental, gest\u00e3o urbana e resili\u00eancia clim\u00e1tica.<\/p>\n<p>O prefeito Luiz Carlos de Aguiar Leite, de Anapu (PA), enfatizou o uso do mapeamento georreferenciado para identificar \u00e1reas vulner\u00e1veis e planejar a realoca\u00e7\u00e3o de fam\u00edlias expostas a enchentes. Tamb\u00e9m apresentou o modelo local de desenvolvimento baseado em pequenas ind\u00fastrias do cacau, energia solar e fundos comunit\u00e1rios, combinando gera\u00e7\u00e3o de renda, conserva\u00e7\u00e3o da floresta e adapta\u00e7\u00e3o \u00e0s mudan\u00e7as clim\u00e1ticas.<\/p>\n<p>Na sequ\u00eancia, a diretora Inamara Santos M\u00e9lo, do Departamento de Pol\u00edticas para Adapta\u00e7\u00e3o e Resili\u00eancia do Minist\u00e9rio do Meio Ambiente (MMA), detalhou a estrat\u00e9gia federal por meio do programa Adapta Cidades, que j\u00e1 envolve 581 munic\u00edpios e tem como meta alcan\u00e7ar 2 mil at\u00e9 2035. Ela defendeu a inclus\u00e3o do seguro como instrumento essencial na agenda de adapta\u00e7\u00e3o. \u201cPrecisamos incorporar o seguro \u00e0s pol\u00edticas p\u00fablicas para ampliar a capacidade adaptativa das cidades\u201d, disse.<\/p>\n<p>Encerrando a perspectiva internacional, Swenja Surminski, diretora de Clima e Sustentabilidade da Marsh McLennan, refor\u00e7ou que resili\u00eancia deixou de ser escolha e passou a ser necessidade. Ela destacou que 22% da popula\u00e7\u00e3o urbana da Am\u00e9rica Latina j\u00e1 vive sob risco de enchentes, uma porcentagem que pode chegar a 30% com o aquecimento global. Swenja tamb\u00e9m mostrou como dados, modelagem de risco e seguros param\u00e9tricos est\u00e3o permitindo solu\u00e7\u00f5es mais eficientes e acess\u00edveis. Para ela, \u201cn\u00e3o se trata mais de risco, mas de realidade\u201d, e pa\u00edses que n\u00e3o tratarem a resili\u00eancia como investimento arcar\u00e3o com custos muito maiores no futuro.<\/p>\n<p><strong>Estrat\u00e9gias municipais para infraestruturas resilientes<\/strong><\/p>\n<p>Mediado por Pedro Werneck, gerente de Sustentabilidade da CNseg, o painel <strong>\u201cPlanejar, construir e cuidar: estrat\u00e9gias municipais para infraestruturas resilientes\u201d<\/strong> reuniu especialistas para discutir como transformar planejamento urbano, governan\u00e7a e engenharia em respostas concretas diante do avan\u00e7o dos eventos clim\u00e1ticos extremos.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01ba58c elementor-widget elementor-widget-image\" data-id=\"01ba58c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"354\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/4-2000x885.jpg\" class=\"attachment-large size-large wp-image-10442\" alt=\"\" srcset=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/4-2000x885.jpg 2000w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/4-300x133.jpg 300w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/4-768x340.jpg 768w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/4-1536x680.jpg 1536w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/4-2048x906.jpg 2048w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/4-18x8.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Painel 2- Planejar, Construir e Cuidar: Estrat\u00e9gias Municipais Para a Promo\u00e7\u00e3o de Infraestruturas Resilientes<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbd1a67 elementor-widget elementor-widget-text-editor\" data-id=\"dbd1a67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pedro abriu o debate destacando a import\u00e2ncia dos dados preditivos para pol\u00edticas p\u00fablicas mais eficazes e lembrou que a nova ferramenta de avalia\u00e7\u00e3o de riscos clim\u00e1ticos da CNseg amplia o acesso \u00e0 informa\u00e7\u00e3o. \u201cDados preditivos deixaram de ser op\u00e7\u00e3o. S\u00e3o condi\u00e7\u00e3o para qualquer estrat\u00e9gia s\u00e9ria de adapta\u00e7\u00e3o.\u201d<\/p>\n<p>A gerente de Sustentabilidade e Resili\u00eancia da CNM, Cl\u00e1udia Lins, enfatizou que o maior desafio dos munic\u00edpios \u00e9 estruturar diagn\u00f3sticos consistentes em meio \u00e0 falta de dados locais, equipes t\u00e9cnicas reduzidas e aus\u00eancia de financiamento est\u00e1vel. Ela lembrou que muitos gestores ainda dependem de s\u00e9ries hist\u00f3ricas que j\u00e1 n\u00e3o refletem o clima atual. \u201cN\u00e3o existe planejamento sem diagn\u00f3stico e n\u00e3o existe diagn\u00f3stico sem dados que dialoguem com a realidade de cada territ\u00f3rio\u201d, afirmou, refor\u00e7ando a import\u00e2ncia do federalismo clim\u00e1tico e da inclus\u00e3o dos munic\u00edpios na formula\u00e7\u00e3o das pol\u00edticas nacionais.<\/p>\n<p>J\u00e1 Karla Fran\u00e7a, analista de Planejamento Territorial e Habita\u00e7\u00e3o da CNM, destacou que apenas 50% dos munic\u00edpios brasileiros possuem plano diretor e, mesmo entre esse grupo, poucos incorporam diretrizes clim\u00e1ticas. Ela citou a fragilidade dos c\u00f3digos de obras, a aus\u00eancia de governan\u00e7a urbana qualificada e a dificuldade das cidades pequenas e m\u00e9dias em adaptar normas e instrumentos para a lente clim\u00e1tica. Karla trouxe exemplos de munic\u00edpios que avan\u00e7aram ao integrar solu\u00e7\u00f5es baseadas na natureza, revisar instrumentos urban\u00edsticos e atuar em cons\u00f3rcios. \u201cSem planejamento, n\u00e3o h\u00e1 resili\u00eancia; e sem financiamento, planejamento n\u00e3o sai do papel\u201d, sintetizou.<\/p>\n<p>Encerrando o painel, Haiany Cristina Ribeiro de Miranda, especialista em Engenharia Ambiental da Nippon Koei (Tokio), apresentou tecnologias promissoras para o contexto brasileiro, como modelagens hidrol\u00f3gicas de alta resolu\u00e7\u00e3o, integra\u00e7\u00e3o de GIS e BIM, sensores IoT e sistemas de alerta precoce.\u00a0<\/p>\n<p>Ela destacou a import\u00e2ncia de adaptar solu\u00e7\u00f5es internacionais \u00e0s realidades locais e lembrou que o Brasil ainda investe muito mais em reconstru\u00e7\u00e3o do que em preven\u00e7\u00e3o. \u201cO pa\u00eds dedica 70% dos recursos ao p\u00f3s-desastre e apenas 2% \u00e0 preven\u00e7\u00e3o. Precisamos inverter essa equa\u00e7\u00e3o.\u201d<\/p>\n<p><strong>Capacita\u00e7\u00e3o e governan\u00e7a para lidar com extremos clim\u00e1ticos<\/strong><\/p>\n<p>O \u00faltimo painel do dia, <strong>\u201cA capacidade municipal de enfrentamento de desastres e o desafio dos extremos clim\u00e1ticos\u201d<\/strong>, trouxe uma discuss\u00e3o pragm\u00e1tica sobre a pergunta que norteou toda a tarde: como preparar munic\u00edpios para enfrentar desastres que j\u00e1 n\u00e3o s\u00e3o exce\u00e7\u00e3o, mas rotina?<\/p>\n<p>Sob a media\u00e7\u00e3o de Luciana Dall\u2019Agnol, superintendente de Sustentabilidade da CNseg, o painel debateu estrat\u00e9gias reais de refor\u00e7o institucional. Luciana destacou a mudan\u00e7a de paradigma do setor de seguros, afirmando que \u201co setor de seguros tem trazido para si a responsabilidade de se colocar em um posicionamento estrat\u00e9gico nessa agenda de clima\u201d.<\/p>\n<p>A analista de Defesa Civil da CNM, Ingrid Ferreira Lima, trouxe \u00e0 mesa n\u00fameros que revelam o tamanho do desafio. Estudo recente da Confedera\u00e7\u00e3o mostrou que 12% dos munic\u00edpios n\u00e3o executam nenhuma a\u00e7\u00e3o exclusiva de Defesa Civil, enquanto 70% contam com or\u00e7amento de at\u00e9 R$ 50 mil para preven\u00e7\u00e3o e resposta, valor insuficiente para cumprir as 18 obriga\u00e7\u00f5es previstas na Pol\u00edtica Nacional de Prote\u00e7\u00e3o e Defesa Civil.\u00a0<\/p>\n<p>Para agravar o quadro, 43% das Defesas Civis municipais t\u00eam apenas tr\u00eas servidores para gerir todas as etapas, da preven\u00e7\u00e3o \u00e0 reconstru\u00e7\u00e3o. \u201cUm Brasil s\u00f3 ser\u00e1 resiliente quando os munic\u00edpios forem resilientes\u201d, afirmou Ingrid, refor\u00e7ando a urg\u00eancia de mais recursos, capacita\u00e7\u00e3o e protagonismo local.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7957556 elementor-widget elementor-widget-image\" data-id=\"7957556\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"354\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/3-2000x885.jpg\" class=\"attachment-large size-large wp-image-10441\" alt=\"\" srcset=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/3-2000x885.jpg 2000w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/3-300x133.jpg 300w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/3-768x340.jpg 768w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/3-1536x680.jpg 1536w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/3-2048x906.jpg 2048w, https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/3-18x8.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Painel 3 - A Capacidade Municipal de Enfrentamento de Desastres e o Desafio dos Extremos Clim\u00e1ticos<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c118f9c elementor-widget elementor-widget-text-editor\" data-id=\"c118f9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A urbanista Leticia Sabino, diretora-presidente do Instituto Caminhabilidade, focou na rela\u00e7\u00e3o entre planejamento urbano, desigualdade e vulnerabilidade clim\u00e1tica. Ela criticou o modelo urbano centrado no autom\u00f3vel e defendeu a caminhabilidade como eixo de mitiga\u00e7\u00e3o e adapta\u00e7\u00e3o. \u201cO planejamento que fizemos at\u00e9 agora n\u00e3o funciona. Adaptar as cidades significa colocar as pessoas no centro e reduzir dist\u00e2ncias\u201d, disse, apresentando exemplos de Paris, Seul e iniciativas brasileiras em Fortaleza e Sobral. Para Leticia, solu\u00e7\u00f5es descentralizadas, de escala de bairro, s\u00e3o fundamentais para proteger mulheres, crian\u00e7as, idosos e moradores das periferias, grupos que mais caminham e os que mais sofrem com calor extremo, enchentes e infraestrutura prec\u00e1ria.<\/p>\n<p>Na perspectiva institucional e financeira, Larissa Menescal, especialista em Pol\u00edticas P\u00fablicas da InREDE, e Jardel Lu\u00eds Carpes, diretor de Riscos da Caixa Econ\u00f4mica Federal, convergiram na mesma conclus\u00e3o: sem integra\u00e7\u00e3o e governan\u00e7a, nenhuma estrat\u00e9gia se sustenta.\u00a0<\/p>\n<p>Larissa destacou os gargalos de fragmenta\u00e7\u00e3o e descontinuidade, defendendo institutos de planejamento capazes de articular diferentes \u00e1reas e transformar dados em a\u00e7\u00e3o concreta. \u201cNunca tivemos tantos dados \u2014 o desafio agora \u00e9 fazer com que eles orientem decis\u00f5es no territ\u00f3rio.\u201d Jardel, por sua vez, apresentou instrumentos como o FEP e o novo Fundo Garantidor de Cr\u00e9dito para PPPs (FGC 3P), lan\u00e7ado na COP30, que ampliam a capacidade dos munic\u00edpios de acessar financiamentos de resili\u00eancia. Para ele, o futuro depende de coordena\u00e7\u00e3o econ\u00f4mica: \u201cPrecisamos equilibrar os incentivos para que a adapta\u00e7\u00e3o seja vi\u00e1vel para todos.\u201d<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28fcb53 elementor-widget elementor-widget-heading\" data-id=\"28fcb53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Confira a transmiss\u00e3o dos pain\u00e9is da tarde do dia 19\/11<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85abf87 elementor-widget elementor-widget-video\" data-id=\"85abf87\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=Q4pKkRbohPU&quot;,&quot;start&quot;:80,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af86a22 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"af86a22\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrossel de imagens\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NDMsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0xLmpwZyIsInNsaWRlc2hvdyI6ImFmODZhMjIifQ%3D%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-1.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-1-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (1)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NDQsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0yLmpwZyIsInNsaWRlc2hvdyI6ImFmODZhMjIifQ%3D%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-2.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-2-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (2)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (3)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NDUsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0zLmpwZyIsInNsaWRlc2hvdyI6ImFmODZhMjIifQ%3D%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-3.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-3-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (3)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (4)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NDYsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS00LmpwZyIsInNsaWRlc2hvdyI6ImFmODZhMjIifQ%3D%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-4.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-4-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (4)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (5)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NDcsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS01LmpwZyIsInNsaWRlc2hvdyI6ImFmODZhMjIifQ%3D%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-5.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-5-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (5)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (6)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NDgsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS02LmpwZyIsInNsaWRlc2hvdyI6ImFmODZhMjIifQ%3D%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-6.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-6-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (6)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (7)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NDksInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS03LmpwZyIsInNsaWRlc2hvdyI6ImFmODZhMjIifQ%3D%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-7.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-7-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (7)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (8)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTAsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS04LmpwZyIsInNsaWRlc2hvdyI6ImFmODZhMjIifQ%3D%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-8.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-8-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (8)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (9)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTEsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS05LmpwZyIsInNsaWRlc2hvdyI6ImFmODZhMjIifQ%3D%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-9.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-9-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (9)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (10)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTIsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0xMC5qcGciLCJzbGlkZXNob3ciOiJhZjg2YTIyIn0%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-10.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-10-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (10)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (11)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTMsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0xMS5qcGciLCJzbGlkZXNob3ciOiJhZjg2YTIyIn0%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-11.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-11-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (11)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (12)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTQsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0xMi5qcGciLCJzbGlkZXNob3ciOiJhZjg2YTIyIn0%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-12.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-12-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (12)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (13)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTUsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0xMy5qcGciLCJzbGlkZXNob3ciOiJhZjg2YTIyIn0%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-13.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-13-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (13)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (14)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTYsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0xNC5qcGciLCJzbGlkZXNob3ciOiJhZjg2YTIyIn0%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-14.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-14-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (14)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (15)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTcsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0xNS5qcGciLCJzbGlkZXNob3ciOiJhZjg2YTIyIn0%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-15.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-15-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (15)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (16)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTgsInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0xNi5qcGciLCJzbGlkZXNob3ciOiJhZjg2YTIyIn0%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-16.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-16-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (16)\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 de 17\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"af86a22\" data-elementor-lightbox-title=\"Casa do seguro_19-11-2025-tarde (17)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTA0NTksInVybCI6Imh0dHBzOlwvXC9jYXNhZG9zZWd1cm8ub3JnLmJyXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8xMVwvQ2FzYS1kby1zZWd1cm9fMTktMTEtMjAyNS10YXJkZS0xNy5qcGciLCJzbGlkZXNob3ciOiJhZjg2YTIyIn0%3D\" href=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-17.jpg\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-seguro_19-11-2025-tarde-17-150x150.jpg\" alt=\"Casa do seguro_19-11-2025-tarde (17)\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9edcd54 elementor-widget elementor-widget-heading\" data-id=\"9edcd54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sobre a Casa do Seguro<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-684d5bf elementor-widget elementor-widget-text-editor\" data-id=\"684d5bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A sustentabilidade \u00e9 a espinha dorsal da \u201c<strong>Casa do Seguro<\/strong>\u201d, iniciativa in\u00e9dita da <strong>CNseg<\/strong> (Confedera\u00e7\u00e3o Nacional das Seguradoras) para inserir o setor nas discuss\u00f5es da COP30, a Confer\u00eancia das Na\u00e7\u00f5es Unidas sobre Mudan\u00e7as Clim\u00e1ticas, que acontece em Bel\u00e9m (PA).<\/p>\n<p>Al\u00e9m da programa\u00e7\u00e3o de conte\u00fado, a \u201c<strong>Casa do Seguro<\/strong>\u201d promove iniciativas de responsabilidade social, prestigiando a economia e a m\u00e3o de obra locais. O projeto \u00e9 ambientalmente respons\u00e1vel e foi desenvolvido dentro dos conceitos de evento neutro e res\u00edduo zero, prevendo ainda uso eficiente de \u00e1gua e energia.<\/p>\n<p>Com o apoio de seus empoderadores \u2013<a href=\"https:\/\/www.allianz.com.br\/\">Allianz<\/a>,\u00a0<a href=\"https:\/\/axa.com.br\/\">AXA<\/a>,\u00a0<a href=\"https:\/\/www.bbseguros.com.br\/\">BB Seguros<\/a>,\u00a0<a href=\"https:\/\/www.bradescoseguros.com.br\/clientes\">Bradesco Seguros<\/a>,\u00a0<a href=\"https:\/\/www.caixaseguridade.com.br\/Paginas\/default.aspx\">Caixa Seguridade<\/a>,\u00a0<a href=\"https:\/\/www.mapfre.com.br\/para-voce\/\">MAPFRE<\/a>,\u00a0<a href=\"https:\/\/www.marsh.com\/pt-br\/locations\/brazil.html\">Marsh McLennan<\/a>,\u00a0<a href=\"https:\/\/www.portoseguro.com.br\/\">Porto<\/a>,\u00a0<a href=\"https:\/\/www.prudential.com.br\/\">Prudential<\/a>\u00a0e\u00a0<a href=\"https:\/\/www.tokiomarine.com.br\/\">Tokio Marine<\/a> \u2013\u00a0 a Casa funciona em 1,6 mil m\u00b2 de \u00e1rea \u00fatil, acomodando plen\u00e1ria com 100 lugares, seis salas de reuni\u00e3o, <em>business lounges,<\/em>\u00a0est\u00fadio para grava\u00e7\u00e3o de podcasts, sala de imprensa, espa\u00e7o de conviv\u00eancia e \u00e1rea para exposi\u00e7\u00f5es art\u00edsticas e apresenta\u00e7\u00f5es culturais.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c9f2e elementor-widget elementor-widget-heading\" data-id=\"34c9f2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">COMPARTILHE<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6af7c25 elementor-share-buttons--view-icon elementor-share-buttons--skin-minimal elementor-share-buttons--shape-rounded elementor-share-buttons--color-custom elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"6af7c25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-whatsapp\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_x-twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no x-twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-x-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_email\" role=\"button\" tabindex=\"0\" aria-label=\"Compartilhar no email\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-envelope\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M502.3 190.8c3.9-3.1 9.7-.2 9.7 4.7V400c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V195.6c0-5 5.7-7.8 9.7-4.7 22.4 17.4 52.1 39.5 154.1 113.6 21.1 15.4 56.7 47.8 92.2 47.6 35.7.3 72-32.8 92.3-47.6 102-74.1 131.6-96.3 154-113.7zM256 320c23.2.4 56.6-29.2 73.4-41.4 132.7-96.3 142.8-104.7 173.4-128.7 5.8-4.5 9.2-11.5 9.2-18.9v-19c0-26.5-21.5-48-48-48H48C21.5 64 0 85.5 0 112v19c0 7.4 3.4 14.3 9.2 18.9 30.6 23.9 40.7 32.4 173.4 128.7 16.8 12.2 50.2 41.8 73.4 41.4z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c284426 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"c284426\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c40a4e premium-blog-align-left elementor-widget elementor-widget-premium-addon-blog\" data-id=\"3c40a4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"premium-addon-blog.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t\n\n\t\t\t\t<div class=\"premium-blog-wrap  premium-blog-list\" data-page=\"10436\">\n\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/de-belem-a-cop31-casa-do-seguro-lanca-forca-tarefa-global-de-resiliencia-climatica\/\" target=\"_blank\">\n\t\t\t\tDe Bel\u00e9m \u00e0 COP31: Casa do Seguro lan\u00e7a for\u00e7a-tarefa global de resili\u00eancia clim\u00e1tica\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>21\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/cnseg-lanca-solucao-conformidade-socioambiental-para-o-seguro-rural\/\" target=\"_blank\">\n\t\t\t\tCNseg lan\u00e7a solu\u00e7\u00e3o Conformidade Socioambiental para o Seguro Rural\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>21\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/como-o-seguro-rural-pode-transformar-o-agro-diante-da-crise-climatica\/\" target=\"_blank\">\n\t\t\t\tComo o seguro rural pode transformar o agro diante da crise clim\u00e1tica?\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>20\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/avanco-das-praticas-regenerativas-abre-caminho-para-seguros-rurais-mais-personalizados\/\" target=\"_blank\">\n\t\t\t\tAvan\u00e7o das pr\u00e1ticas regenerativas abre caminho para seguros rurais mais personalizados\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>20\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/do-risco-ao-planejamento-como-seguros-ciencia-e-municipios-estao-moldando-a-resiliencia-climatica\/\" target=\"_blank\">\n\t\t\t\tDo risco ao planejamento: como seguros, ci\u00eancia e munic\u00edpios est\u00e3o moldando a resili\u00eancia clim\u00e1tica\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>19\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/seguros-infraestrutura-e-natureza-os-caminhos-para-fortalecer-a-resiliencia-urbana-na-america-latina\/\" target=\"_blank\">\n\t\t\t\tSeguros, infraestrutura e natureza: os caminhos para fortalecer a resili\u00eancia urbana na Am\u00e9rica Latina\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>19\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/cop30-cnseg-lanca-ferramenta-regionalizada-contra-risco-de-inundacao\/\" target=\"_blank\">\n\t\t\t\tCOP30: CNseg lan\u00e7a ferramenta regionalizada contra risco de inunda\u00e7\u00e3o\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>19\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/do-financiamento-a-adaptacao-o-papel-estrategico-do-seguro-na-nova-agenda-da-infraestrutura-brasileira\/\" target=\"_blank\">\n\t\t\t\tDo financiamento \u00e0 adapta\u00e7\u00e3o: o papel estrat\u00e9gico do seguro na nova agenda da infraestrutura brasileira\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>18\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/inovacao-e-peca-chave-para-adaptacao-climatica-e-avanco-do-mercado-de-carbono\/\" target=\"_blank\">\n\t\t\t\tInova\u00e7\u00e3o \u00e9 pe\u00e7a chave para adapta\u00e7\u00e3o clim\u00e1tica e avan\u00e7o do mercado de carbono\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>18\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"premium-blog-post-outer-container\" data-total=\"10\">\n\t\t\t<div class=\"premium-blog-post-container premium-blog-skin-classic\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-blog-content-wrapper empty-thumb\">\n\n\t\t\t\t\t<div class=\"premium-blog-inner-container\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"premium-blog-entry-title\">\n\t\t\t<a href=\"https:\/\/casadoseguro.org.br\/en\/como-a-parceria-entre-cooperativas-e-seguros-prepara-o-brasil-para-enfrentar-desastres-climaticos\/\" target=\"_blank\">\n\t\t\t\tComo a parceria entre cooperativas e seguros prepara o Brasil para enfrentar desastres clim\u00e1ticos\t\t\t<\/a>\n\t\t<\/h2>\n\t\t\t\t<div class=\"premium-blog-entry-meta\">\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"premium-blog-meta-separator\">\u2022<\/span>\n\t\t\t\t<div class=\"premium-blog-post-time premium-blog-meta-data\">\n\t\t\t\t\t<i class=\"fa fa-calendar-alt\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t<span>17\/11\/2025<\/span>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Conhecer o risco \u00e9 o primeiro passo\u00a0para evit\u00e1-lo. E\u00a0o Brasil n\u00e3o pode mais caminhar \u00e0s cegas diante dos eventos clim\u00e1ticos extremos. Essa foi a mensagem central de Dyogo Oliveira, presidente da CNseg (Confedera\u00e7\u00e3o\u00a0Nacional das Seguradoras), na abertura do \u201cF\u00f3rum Cidades Resilientes na COP30\u201d, realizado na tarde\u00a0desta quarta-feira (19), na Casa do Seguro, em Bel\u00e9m (PA), durante\u00a0a Confer\u00eancia do Clima. <\/p>","protected":false},"author":7,"featured_media":10437,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"rttpg_featured_image_url":{"full":["https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde.jpg",1333,590,false],"landscape":["https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde.jpg",1333,590,false],"portraits":["https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde.jpg",1333,590,false],"thumbnail":["https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde-150x150.jpg",150,150,true],"medium":["https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde-300x133.jpg",300,133,true],"large":["https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde.jpg",800,354,false],"1536x1536":["https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde.jpg",1333,590,false],"2048x2048":["https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde.jpg",1333,590,false],"trp-custom-language-flag":["https:\/\/casadoseguro.org.br\/wp-content\/uploads\/2025\/11\/Casa-do-Seguro-Painel-19-11_tarde-18x8.jpg",18,8,true]},"rttpg_author":{"display_name":"Flavia Freitas","author_link":"https:\/\/casadoseguro.org.br\/en\/author\/flavia-freitascnseg-org-br\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/casadoseguro.org.br\/en\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","rttpg_excerpt":"Conhecer o risco \u00e9 o primeiro passo\u00a0para evit\u00e1-lo. E\u00a0o Brasil n\u00e3o pode mais caminhar \u00e0s cegas diante dos eventos clim\u00e1ticos extremos. Essa foi a mensagem central de Dyogo Oliveira, presidente da CNseg (Confedera\u00e7\u00e3o\u00a0Nacional das Seguradoras), na abertura do \u201cF\u00f3rum Cidades Resilientes na COP30\u201d, realizado na tarde\u00a0desta quarta-feira (19), na Casa do Seguro, em Bel\u00e9m (PA),&hellip;","_links":{"self":[{"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/posts\/10436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/comments?post=10436"}],"version-history":[{"count":4,"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/posts\/10436\/revisions"}],"predecessor-version":[{"id":10462,"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/posts\/10436\/revisions\/10462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/media\/10437"}],"wp:attachment":[{"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/media?parent=10436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/categories?post=10436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casadoseguro.org.br\/en\/wp-json\/wp\/v2\/tags?post=10436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}